{"id":1631,"date":"2025-02-27T11:25:08","date_gmt":"2025-02-27T09:25:08","guid":{"rendered":"https:\/\/galshimron.com\/product\/%d9%81%d8%b3%d8%aa%d8%a7%d9%86-%d8%b1%d9%82%d8%b5-%d8%a7%d8%ad%d8%aa%d8%b1%d8%a7%d9%81%d9%8a-%d8%a8%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d9%85%d9%86-%d9%82%d9%85%d8%a7%d8%b4-%d8%a7%d9%84%d8%a8%d8%a7%d9%8a\/"},"modified":"2026-07-08T20:51:36","modified_gmt":"2026-07-08T17:51:36","slug":"%d9%81%d8%b3%d8%aa%d8%a7%d9%86-%d8%b1%d9%82%d8%b5-%d8%a7%d8%ad%d8%aa%d8%b1%d8%a7%d9%81%d9%8a-%d8%a8%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d9%85%d9%86-%d9%82%d9%85%d8%a7%d8%b4-%d8%a7%d9%84%d8%a8%d8%a7%d9%8a","status":"publish","type":"product","link":"https:\/\/galshimron.com\/ar\/product\/%d9%81%d8%b3%d8%aa%d8%a7%d9%86-%d8%b1%d9%82%d8%b5-%d8%a7%d8%ad%d8%aa%d8%b1%d8%a7%d9%81%d9%8a-%d8%a8%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d9%85%d9%86-%d9%82%d9%85%d8%a7%d8%b4-%d8%a7%d9%84%d8%a8%d8%a7%d9%8a\/","title":{"rendered":"\u0641\u0633\u062a\u0627\u0646 \u0631\u0642\u0635 \u0627\u062d\u062a\u0631\u0627\u0641\u064a \u0628\u062a\u0635\u0645\u064a\u0645 \u0645\u0646 \u0642\u0645\u0627\u0634 \u0627\u0644\u0628\u0627\u064a\u064a\u062a"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0641\u0633\u062a\u0627\u0646 \u0631\u0642\u0635 \u0627\u062d\u062a\u0631\u0627\u0641\u064a \u0628\u062a\u0635\u0645\u064a\u0645 \u0645\u0645\u064a\u0632 \u0645\u0635\u0646\u0648\u0639 \u0645\u0646 \u0642\u0645\u0627\u0634 \u0627\u0644\u0628\u0627\u064a\u064a\u062a \u0627\u0644\u0630\u064a \u064a\u063a\u064a\u0651\u0631 \u0644\u0648\u0646\u0647 \u062d\u0633\u0628 \u0627\u0644\u0625\u0636\u0627\u0621\u0629.<br \/>\n\u064a\u062a\u0645\u064a\u0632 \u0627\u0644\u0641\u0633\u062a\u0627\u0646 \u0628\u062a\u0635\u0645\u064a\u0645 \u063a\u064a\u0631 \u0645\u062a\u0645\u0627\u062b\u0644 \u0645\u0639 \u0634\u0642 \u0639\u0644\u0649 \u0627\u0644\u062c\u0627\u0646\u0628 \u0627\u0644\u0623\u064a\u0645\u0646 \u0648\u0633\u0631\u0648\u0627\u0644 \u0644\u064a\u0643\u0631\u0627 \u0645\u0631\u064a\u062d \u062a\u062d\u062a\u0647.<br \/>\n\u0627\u0644\u0625\u0643\u0633\u0633\u0648\u0627\u0631\u0627\u062a: \u0633\u0648\u0627\u0631\u0627\u0646 \u0645\u062a\u0637\u0627\u0628\u0642\u0627\u0646 \u0644\u0644\u0630\u0631\u0627\u0639\u064a\u0646.<br \/>\n\u0627\u0644\u0645\u0642\u0627\u0633: \u0643\u0648\u0628 \u0635\u062f\u0631 C\u060c \u0645\u0646\u0627\u0633\u0628 \u0644\u0644\u0645\u0642\u0627\u0633\u0627\u062a 38-42.<br \/>\n\u0627\u0644\u0644\u0648\u0646: \u0628\u0646\u0641\u0633\u062c\u064a \u0641\u0627\u062a\u062d.<\/p>\n","protected":false},"featured_media":1562,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[]},"product_brand":[],"product_cat":[83],"product_tag":[],"class_list":["post-1631","product","type-product","status-publish","has-post-thumbnail","product_cat-uncategorized","pa_-97","desktop-align-center","tablet-align-left","mobile-align-left","ast-product-gallery-layout-vertical-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","outofstock","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"spectra_custom_meta":{"rank_math_internal_links_processed":["1"],"stick-header-meta":["default"],"site-sidebar-layout":["default"],"theme-transparent-header-meta":["default"],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"_backorders":["no"],"_download_limit":["-1"],"_download_expiry":["-1"],"_downloadable":["no"],"_manage_stock":["yes"],"_stock_status":["outofstock"],"_sold_individually":["yes"],"_tax_class":[""],"_tax_status":["taxable"],"_virtual":["no"],"total_sales":["0"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_thumbnail_id":["1562"],"rank_math_analytic_object_id":["4"],"rank_math_primary_product_cat":["84"],"_uag_css_file_name":["uag-css-1631.css"],"_regular_price":["700"],"_price":["700"],"_stock":[null],"_wc_average_rating":["0"],"_wc_review_count":["0"],"_product_version":["10.9.3"],"_uag_page_assets":["a:9:{s:3:\"css\";s:11659:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-43990567.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-43990567.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1024px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1024px;height: auto;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:12:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:7;s:10:\"uagb\/image\";i:8;s:14:\"core\/shortcode\";i:9;s:22:\"wpml\/language-switcher\";i:10;s:12:\"core\/details\";i:11;s:17:\"fibosearch\/search\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1782990149\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628.png",1126,2000,false],"thumbnail":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-150x150.png",150,150,true],"medium":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-169x300.png",169,300,true],"medium_large":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-768x1364.png",768,1364,true],"large":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-577x1024.png",577,1024,true],"ufg_200_200":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-200x200.png",200,200,true],"ufg_300_300":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-300x300.png",300,300,true],"ufg_400_400":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-400x400.png",400,400,true],"1536x1536":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-865x1536.png",865,1536,true],"2048x2048":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628.png",1126,2000,false],"woocommerce_thumbnail":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-300x300.png",300,300,true],"woocommerce_single":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-600x1066.png",600,1066,true],"woocommerce_gallery_thumbnail":["https:\/\/galshimron.com\/wp-content\/uploads\/2025\/02\/Photoroom-20250226_223628-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"logicode","author_link":"https:\/\/galshimron.com\/ar\/author\/"},"uagb_comment_info":21,"uagb_excerpt":"\u0641\u0633\u062a\u0627\u0646 \u0631\u0642\u0635 \u0627\u062d\u062a\u0631\u0627\u0641\u064a \u0628\u062a\u0635\u0645\u064a\u0645 \u0645\u0645\u064a\u0632 \u0645\u0635\u0646\u0648\u0639 \u0645\u0646 \u0642\u0645\u0627\u0634 \u0627\u0644\u0628\u0627\u064a\u064a\u062a \u0627\u0644\u0630\u064a \u064a\u063a\u064a\u0651\u0631 \u0644\u0648\u0646\u0647 \u062d\u0633\u0628 \u0627\u0644\u0625\u0636\u0627\u0621\u0629. \u064a\u062a\u0645\u064a\u0632 \u0627\u0644\u0641\u0633\u062a\u0627\u0646 \u0628\u062a\u0635\u0645\u064a\u0645 \u063a\u064a\u0631 \u0645\u062a\u0645\u0627\u062b\u0644 \u0645\u0639 \u0634\u0642 \u0639\u0644\u0649 \u0627\u0644\u062c\u0627\u0646\u0628 \u0627\u0644\u0623\u064a\u0645\u0646 \u0648\u0633\u0631\u0648\u0627\u0644 \u0644\u064a\u0643\u0631\u0627 \u0645\u0631\u064a\u062d \u062a\u062d\u062a\u0647. \u0627\u0644\u0625\u0643\u0633\u0633\u0648\u0627\u0631\u0627\u062a: \u0633\u0648\u0627\u0631\u0627\u0646 \u0645\u062a\u0637\u0627\u0628\u0642\u0627\u0646 \u0644\u0644\u0630\u0631\u0627\u0639\u064a\u0646. \u0627\u0644\u0645\u0642\u0627\u0633: \u0643\u0648\u0628 \u0635\u062f\u0631 C\u060c \u0645\u0646\u0627\u0633\u0628 \u0644\u0644\u0645\u0642\u0627\u0633\u0627\u062a 38-42. \u0627\u0644\u0644\u0648\u0646: \u0628\u0646\u0641\u0633\u062c\u064a \u0641\u0627\u062a\u062d.","_links":{"self":[{"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/product\/1631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/comments?post=1631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/media\/1562"}],"wp:attachment":[{"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/media?parent=1631"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/product_brand?post=1631"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/product_cat?post=1631"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galshimron.com\/ar\/wp-json\/wp\/v2\/product_tag?post=1631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}