{"id":771,"date":"2024-11-02T00:51:01","date_gmt":"2024-11-01T22:51:01","guid":{"rendered":"https:\/\/galshimron.com\/events-booking\/"},"modified":"2024-11-02T00:51:01","modified_gmt":"2024-11-01T22:51:01","slug":"events-booking","status":"publish","type":"page","link":"https:\/\/galshimron.com\/en\/events-booking\/","title":{"rendered":"Events Booking"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-c26d0a94 alignfull uagb-is-root-container\"><div class=\"uagb-container__video-wrap\"><video autoplay=\"\" loop=\"\" muted=\"\" playsinline=\"\"><source src=\"https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/2515639_Dancer_Dance_1280x720.mp4\" type=\"video\/mp4\"><\/source><\/video><\/div><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-509d7368\"><h1 class=\"uagb-heading-text\">Events Booking<\/h1><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0e75416a\"><h2 class=\"uagb-heading-text\">Booking bachelorette parties | henna | Weddings Birthdays | private events<\/h2><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b3cab6c0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n\t\t\t<div class=\"wp-block-uagb-post-grid uagb-post-grid  uagb-post__image-position-top uagb-post__image-enabled uagb-block-675415ae     uagb-post__items uagb-post__columns-3 is-grid uagb-post__columns-tablet-2 uagb-post__columns-mobile-1 uagb-post__equal-height\" data-total=\"1\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/galshimron.com\/en\/henna-performances-wedding\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-inherit'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/2-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/2-1.jpg 600w, https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/2-1-300x150.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/galshimron.com\/en\/henna-performances-wedding\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">Henna performances \/ wedding<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\tGal Shimron, a first class belly dancer in Israel, brings an authentic and immersive oriental experience to parties and weddings. With spectacular solo dances,&#8230;\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/galshimron.com\/en\/henna-performances-wedding\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u05dc\u05d7\u05d1\u05d9\u05dc\u05d5\u05ea \u05d4\u05de\u05dc\u05d0\u05d5\u05ea<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/galshimron.com\/en\/performances-at-bachelorette-parties-womens-evenings\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-inherit'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/3-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/3-1.jpg 600w, https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/3-1-300x150.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/galshimron.com\/en\/performances-at-bachelorette-parties-womens-evenings\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">Performances at bachelorette parties \/ women&#8217;s evenings<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\tGal Shimron, a charismatic and captivating belly dancer, creates a fun and unforgettable experience at bachelorette parties and ladies&#8217; evenings. With spectacular solo dances,&#8230;\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/galshimron.com\/en\/performances-at-bachelorette-parties-womens-evenings\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u05dc\u05d7\u05d1\u05d9\u05dc\u05d5\u05ea \u05d4\u05de\u05dc\u05d0\u05d5\u05ea<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/galshimron.com\/en\/birthday-packages\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-inherit'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/4.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/4.jpg 600w, https:\/\/galshimron.com\/wp-content\/uploads\/2024\/11\/4-300x150.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/galshimron.com\/en\/birthday-packages\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">Birthday packages<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\tGal Shemron, a spectacular and charismatic belly dancer, brings an exciting and unique experience to birthdays. With breathtaking solo dances, special props and the&#8230;\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/galshimron.com\/en\/birthday-packages\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">\u05dc\u05d7\u05d1\u05d9\u05dc\u05d5\u05ea \u05d4\u05de\u05dc\u05d0\u05d5\u05ea<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Events Booking Booking bachelorette parties | henna | Weddings Birthdays | private events<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"class_list":["post-771","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"adv-header-id-meta":[""],"stick-header-meta":[""],"site-post-title":["disabled"],"theme-transparent-header-meta":[""],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_wpml_word_count":["{\"total\":17,\"to_translate\":{\"ar\":17,\"he\":17,\"ru\":17}}"],"_wp_page_template":[""],"rank_math_internal_links_processed":["1"],"rank_math_analytic_object_id":["54"],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"footer-sml-layout":[""],"header-main-stick-meta":[""],"header-above-stick-meta":[""],"header-below-stick-meta":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-featured-img":[""],"ast-breadcrumbs-content":[""],"ast-banner-title-visibility":[""],"ast-global-header-display":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"_uag_css_file_name":["uag-css-771.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:2;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:2;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:1;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1776769017"],"_uag_page_assets":["a:9:{s:3:\"css\";s:42016:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}\ufeff.uagb-post-grid{margin:0 auto;position:relative}.uagb-post-grid:not(.is-grid) .uagb-post__inner-wrap{background-clip:content-box !important}.uagb-post-grid .uagb-post__inner-wrap{transition:box-shadow .2s ease;overflow:hidden}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.default{margin:5px 5px 5px 0}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{background:#444;color:#fff;border-radius:2px;flex-direction:row;align-items:flex-end;padding:6px 8px;line-height:1;margin-right:5px;margin-bottom:20px}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color:#fff}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy a{text-decoration:none;color:inherit}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__image .uagb-post__image-equal-height{display:block;height:0;padding-bottom:66.67%;overflow:hidden}.uagb-post-grid .uagb-post__load-more-wrap{width:100%;position:absolute;bottom:-30px}.uagb-post-grid .uagb-post__load-more-wrap .uagb-post-pagination-button{cursor:pointer}.uagb-post-grid .uagb-post__load-more-wrap a{color:inherit}.uagb-post-grid.is-grid article{float:left;display:inline-block}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:nth-last-child(2){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:last-child{position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(3){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(2){position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__inner-wrap,.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a{display:block;height:0;overflow:hidden;position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-2-3{padding-bottom:66%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-9-16{padding-bottom:56.25%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-2{padding-bottom:50%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-1{padding-bottom:67%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit{padding-bottom:0;height:auto}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit img{position:unset !important}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a[class^=uagb-image-ratio-]>img{position:absolute;height:100%}.uagb-post-grid.uagb-post__items.is-masonry{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap}.uagb-post-grid.uagb-post__items.is-carousel{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap;width:100%;visibility:hidden}.uagb-post-grid.is-grid .uagb-post__inner-wrap{height:max-content}.uagb-post-grid.is-grid.uagb-post__equal-height .uagb-post__inner-wrap{height:auto}.uagb-post-grid.is-masonry .uagb-post__inner-wrap{height:auto}.uagb-post-grid .uagb-post__author span,.uagb-post-grid .uagb-post__comment span,.uagb-post-grid .uagb-post__taxonomy span,.uagb-post-grid .uagb-post__date span{font-size:inherit;line-height:inherit;width:inherit;height:inherit;margin-right:4px;vertical-align:bottom}.uagb-post-grid.uagb-post__columns-8:not(.is-grid) article{width:12.5%}.uagb-post-grid.uagb-post__columns-7:not(.is-grid) article{width:14.28%}.uagb-post-grid.uagb-post__columns-6:not(.is-grid) article{width:16.66%}.uagb-post-grid.uagb-post__columns-5:not(.is-grid) article{width:20%}.uagb-post-grid.uagb-post__columns-4:not(.is-grid) article{width:25%}.uagb-post-grid.uagb-post__columns-3:not(.is-grid) article{width:33.33%}.uagb-post-grid.uagb-post__columns-2:not(.is-grid) article{width:50%}.uagb-post-grid.uagb-post__columns-1:not(.is-grid) article{width:100%}@media only screen and (max-width: 600px){.uagb-post-grid div[class*=columns].is-grid{grid-template-columns:1fr}}.uagb-post-grid .uagb-post__image img{display:block;width:100%;height:auto;max-width:100%}.uagb-post-grid .uagb-post__title{margin-top:0;margin-bottom:0;word-break:break-word}.uagb-post-grid .uagb-post__title a{color:inherit;box-shadow:none;transition:.3s ease;text-decoration:none}.uagb-post-grid .uagb-post__title a:hover{text-decoration:none}.uagb-post-grid .uagb-post__title a:focus{text-decoration:none}.uagb-post-grid .uagb-post__title a:active{text-decoration:none}.uagb-post-grid .uagb-post-grid-byline>*{margin-right:10px}.uagb-post-grid .uagb-post-grid-byline,.uagb-post-grid .uagb-post__taxonomy{text-transform:capitalize;font-size:14px;font-weight:500;line-height:23px;text-decoration:none}.uagb-post-grid .uagb-post-grid-byline a,.uagb-post-grid .uagb-post-grid-byline a:focus,.uagb-post-grid .uagb-post-grid-byline a:active{color:inherit;font-size:inherit;text-decoration:none}.uagb-post-grid .uagb-post__title a,.uagb-post-grid .uagb-post__title a:focus,.uagb-post-grid .uagb-post__title a:active{color:inherit;font-size:inherit}.uagb-post-grid .uagb-post__author,.uagb-post-grid .uagb-post__date,.uagb-post-grid .uagb-post__comment{display:inline-block;word-break:break-all}.uagb-post-grid .uagb-post__author:not(:last-child)::after,.uagb-post-grid .uagb-post__date:not(:last-child)::after,.uagb-post-grid .uagb-post__comment:not(:last-child)::after{content:\"\u00b7\";vertical-align:middle;align-self:center;margin:0 5px;line-height:1}.uagb-post-grid .uagb-post__comment,.uagb-post-grid .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__author a{box-shadow:none}.uagb-post-grid .uagb-post__author a:hover{color:inherit;box-shadow:0 -1px 0 inset}.uagb-post-grid .uagb-post__excerpt{word-break:break-word}.uagb-post-grid .uagb-post__inner-wrap p:last-of-type{margin-bottom:0}.uagb-post-grid .uagb-post__cta{border:none;display:inline-block;background:none}.uagb-post-grid .uagb-post__cta .ast-outline-button{display:inline-flex}.uagb-post-grid .uagb-post__excerpt p{color:inherit}.is-grid.uagb-post__items{display:grid}.wp-block-uagb-post-grid .uagb-post-pagination-wrap{grid-column:1\/-1}.uagb-post__image-position-background .uagb-post__link-complete-box{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.uagb-post__image-position-background.uagb-post__image-enabled .uagb-post__text{color:#fff}.uagb-post__image-position-background .uagb-post__text{opacity:1;position:relative;z-index:10;overflow:hidden}.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative;width:100%}.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted,.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.default{position:relative;z-index:999}.uagb-post__image-position-background .uagb-post__image img{position:absolute;width:auto;height:auto;min-width:100%;max-width:none;left:50%;top:50%;transform:translate(-50%, -50%);min-height:100%}.uagb-post__image-position-background .uagb-post__image{background-size:cover;background-repeat:no-repeat;background-position:center;overflow:hidden;text-align:center;position:absolute;left:0;top:0;width:100%;height:100%;z-index:2}.uagb-post__image-position-background .uagb-post__image::before{content:\"\";position:absolute;left:0;top:0;width:100%;height:100%;z-index:1;background-color:hsla(0,0%,100%,.5)}.uagb-slick-carousel .is-carousel{padding:0}.uagb-slick-carousel ul.slick-dots{transform:unset;position:relative;padding:unset}.uagb-slick-carousel .slick-prev:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel .slick-next:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel ul.slick-dots li button:not(:hover):not(:active):not(.has-background){background-color:unset}.uagb-post-grid[data-equal-height=yes] .uagb-post__inner-wrap{display:inline-block;height:100%}.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;right:auto}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:-45px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:auto;right:-45px}.uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:25px;z-index:1}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:auto;right:25px}.uagb-post__arrow-inside.uagb-post-grid .slick-next{right:25px}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-next{left:25px;right:auto}.uagb-post-grid.is-grid article,.uagb-post-grid.is-masonry article,.uagb-post-grid.is-carousel article{box-sizing:border-box}@media(max-width: 976px){.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:15px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:auto;right:15px}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:15px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:15px;right:auto}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-8 article{width:12.5%}}@media(max-width: 767px){:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-8 article{width:12.5%}}.entry .entry-content .uagb-post-grid a{text-decoration:none}.uagb-post-pagination-wrap{display:flex;width:100%;flex-wrap:wrap}.uagb-post-pagination-wrap a.page-numbers,.uagb-post-pagination-wrap span.page-numbers.current{padding:5px 10px;margin:0;display:flex;margin-right:4px;margin-bottom:5px}.uagb-post-grid .uagb-post-inf-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.uagb-post-grid .uagb-post-inf-loader div{width:18px;height:18px;background-color:#0085ba;-webkit-border-radius:100%;border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-next{right:0}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.wp-block-uagb-container.uagb-block-c26d0a94 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c26d0a94 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c26d0a94 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c26d0a94 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c26d0a94 .uagb-container__video-wrap video{opacity: 0.5;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c26d0a94{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c26d0a94 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1300px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c26d0a94 .uagb-container__video-wrap{background: #f7d7ad;;border-color: inherit;}.wp-block-uagb-container.uagb-block-c26d0a94 > div:not(.uagb-container__video-wrap):not(.uagb-container__shape){position: relative;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-c26d0a94{flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c26d0a94{min-height: 56vh;box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;}.wp-block-uagb-advanced-heading.uagb-block-509d7368.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;text-shadow: 2px 2px 2px #000000;}.wp-block-uagb-advanced-heading.uagb-block-509d7368.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-509d7368.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-509d7368.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-509d7368.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-509d7368.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-509d7368 .uagb-heading-text{font-size: 100px;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a .uagb-heading-text{font-weight: 200;font-size: 40px;}.wp-block-uagb-container.uagb-block-b3cab6c0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b3cab6c0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b3cab6c0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b3cab6c0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b3cab6c0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b3cab6c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b3cab6c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b3cab6c0{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-675415ae.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 2px 5px -1px #00000070;}.uagb-block-675415ae.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-675415ae:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-675415ae:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-675415ae:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-675415ae:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-675415ae:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-675415ae:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-675415ae .uagb-post__inner-wrap{background: #f6f6f6;text-align: right;}.uagb-block-675415ae .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-675415ae .uagb-post__image {padding-bottom: 15px;}.uagb-block-675415ae .uagb-post__title{padding-bottom: 15px;}.uagb-block-675415ae .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-675415ae .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-675415ae .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-675415ae.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-675415ae.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(3 , minmax(0, 1fr));}.uagb-block-675415ae.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-675415ae .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-675415ae .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-675415ae.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {color: #000000;background: #cc9c61;0: ;0: ;0: ;0: ;0: 5px;0: 5px;0: 5px;0: 5px;0: ;0: none;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-style: none;}.uagb-block-675415ae.uagb-post-grid .uagb-post__inner-wrap .wp-block-button.uagb-post__text.uagb-post__cta a{color: #000000;}.uagb-block-675415ae .uagb-post-pagination-wrap{margin-top: 20px;justify-content: left;margin-left: 10px;}.uagb-block-675415ae .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-675415ae .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-675415ae.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 20px;right: 20px;}.uagb-block-675415ae.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c26d0a94{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c26d0a94 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c26d0a94{min-height: 25vh;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;}.wp-block-uagb-advanced-heading.uagb-block-509d7368 .uagb-heading-text{font-size: 80px;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a .uagb-heading-text{font-size: 28px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b3cab6c0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b3cab6c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b3cab6c0{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-675415ae.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-675415ae.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-675415ae:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-675415ae:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-675415ae.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-675415ae.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-675415ae .uagb-post__cta a{border-style: none;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c26d0a94{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c26d0a94 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-c26d0a94{flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c26d0a94{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;}.wp-block-uagb-advanced-heading.uagb-block-509d7368 .uagb-heading-text{font-size: 50px;}.wp-block-uagb-advanced-heading.uagb-block-0e75416a .uagb-heading-text{font-size: 12px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b3cab6c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b3cab6c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b3cab6c0{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-675415ae.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-675415ae.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-675415ae:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-675415ae:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-675415ae.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-675415ae.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-675415ae.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-43990567.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-43990567.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-43990567.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-43990567.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-aaf4165c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1024px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-aaf4165c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1024px;height: auto;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:16:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:3;s:14:\"uagb\/post-grid\";i:4;s:14:\"core\/paragraph\";i:5;s:11:\"core\/search\";i:6;s:10:\"core\/group\";i:7;s:12:\"core\/heading\";i:8;s:17:\"core\/latest-posts\";i:9;s:20:\"core\/latest-comments\";i:10;s:13:\"core\/archives\";i:11;s:15:\"core\/categories\";i:12;s:10:\"uagb\/image\";i:13;s:14:\"core\/shortcode\";i:14;s:22:\"wpml\/language-switcher\";i:15;s:12:\"core\/details\";i:16;s:17:\"fibosearch\/search\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1782990149\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"ufg_200_200":false,"ufg_300_300":false,"ufg_400_400":false,"1536x1536":false,"2048x2048":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"logicode","author_link":"https:\/\/galshimron.com\/en\/author\/logicode\/"},"uagb_comment_info":0,"uagb_excerpt":"Events Booking Booking bachelorette parties | henna | Weddings Birthdays | private events","_links":{"self":[{"href":"https:\/\/galshimron.com\/en\/wp-json\/wp\/v2\/pages\/771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galshimron.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/galshimron.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/galshimron.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/galshimron.com\/en\/wp-json\/wp\/v2\/comments?post=771"}],"version-history":[{"count":0,"href":"https:\/\/galshimron.com\/en\/wp-json\/wp\/v2\/pages\/771\/revisions"}],"wp:attachment":[{"href":"https:\/\/galshimron.com\/en\/wp-json\/wp\/v2\/media?parent=771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}